{"id":4764,"date":"2015-11-18T11:27:35","date_gmt":"2015-11-18T11:27:35","guid":{"rendered":"https:\/\/idro.es\/?p=4764&#038;lang=pt-pt"},"modified":"2025-10-14T10:20:27","modified_gmt":"2025-10-14T08:20:27","slug":"whats-in-a-food-scientists-fridge","status":"publish","type":"post","link":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/","title":{"rendered":"O que h\u00e1 na geladeira de um cientista alimentar?"},"content":{"rendered":"<p>No laborat\u00f3rio, os nossos cientistas alimentares respeitam uma regra n\u00e3o escrita:<\/p>\n<blockquote><p><strong><em>N\u00e3o importa o qu\u00e3o alto o seu est\u00f4mago ronque, n\u00e3o fa\u00e7a \u2013 em nenhuma circunst\u00e2ncia \u2013 um lanche r\u00e1pido no frigor\u00edfico da cozinha de teste.<\/em><\/strong><\/p><\/blockquote>\n<p>Por que? Porque \u201cChutney de Manga e Menta e P\u00eassego &#8211; 06\/03\/15 &#8211; Estabilidade e amp; An\u00e1lise de Perfil Microbiol\u00f3gico\u201d n\u00e3o se destina ao consumo.<\/p>\n<p>Felizmente, em casa, essas regras n\u00e3o se aplicam. Ent\u00e3o pensamos que seria interessante descobrir quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.<br \/>\n<!--more--><\/p>\n<p><strong>Errol Raghubeer, vice-presidente s\u00eanior de ci\u00eancia e tecnologia HPP<\/strong><br \/>\nMolhos de pimenta. D\u00ea a ele um peda\u00e7o de casca de \u00e1rvore e ele ir\u00e1 para a cidade.<\/p>\n<p><strong>Bick-Ngoc Phan, director, microbiology and food technology<\/strong><br \/>\nSucos e convenientes <a title=\"HPP ready to eat meat\" href=\"https:\/\/www.jbtc.com\/foodtech\/products-and-solutions\/products\/high-pressure-processors\/hpp-applications\/\" target=\"_blank\" rel=\"noopener\">ready-to-eat meat<\/a>.No laborat\u00f3rio, sua paix\u00e3o s\u00e3o os frutos do mar. Em casa, os frios imperam.<\/p>\n<p><strong>David Peck, senior food scientist<\/strong><br \/>\nGuacamole e suco. David \u00e9 um cara que adora carne, mas nem ele consegue resistir a um bom guacamole. Ousamos dizer que \u00e9 melhor do que maionese em hamb\u00fargueres?<\/p>\n<p><strong>Colleen Galieti, food scientist<\/strong><br \/>\n\u201cEu adoro todas as carnes frias naturais. Eles s\u00e3o \u00f3timos para o almo\u00e7o e sem conservantes. E de vez em quando, vou fazer um lanche delicioso <a title=\"HPP for guacamole\" href=\"https:\/\/www.jbtc.com\/foodtech\/products-and-solutions\/products\/high-pressure-processors\/hpp-applications\/\" target=\"_blank\" rel=\"noopener\">guacamole HPP<\/a>.\u201d<\/p>\n<p>Quer saber mais sobre as estrelas da ci\u00eancia alimentar da Avure?<\/p>\n<p>Por exemplo, onde eles veem a ind\u00fastria aliment\u00edcia nos pr\u00f3ximos 25 anos e quais aplica\u00e7\u00f5es futuras de HPP mais os entusiasmam?<\/p>\n<p>Visite nosso novo <a href=\"https:\/\/www.jbtc.com\/foodtech\/products-and-solutions\/products\/high-pressure-processors\/our-team\/\" target=\"_blank\" rel=\"noopener\">equipe de ci\u00eancia alimentar<\/a> p\u00e1gina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No laborat\u00f3rio, os nossos cientistas alimentares respeitam uma regra n\u00e3o escrita: N\u00e3o importa o qu\u00e3o alto o seu est\u00f4mago ronque, n\u00e3o fa\u00e7a \u2013 em nenhuma circunst\u00e2ncia \u2013 um lanche r\u00e1pido no frigor\u00edfico da cozinha de teste. Por que? Porque \u201cChutney de Manga e Menta e P\u00eassego &#8211; 06\/03\/15 &#8211; Estabilidade e amp; An\u00e1lise de Perfil [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[254],"tags":[],"class_list":["post-4764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que h\u00e1 na geladeira de um cientista alimentar? - IDRO<\/title>\n<meta name=\"description\" content=\"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que h\u00e1 na geladeira de um cientista alimentar? - IDRO\" \/>\n<meta property=\"og:description\" content=\"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/\" \/>\n<meta property=\"og:site_name\" content=\"IDRO\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-18T11:27:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T08:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00aa Luz Villa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00aa Luz Villa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/\"},\"author\":{\"name\":\"M\u00aa Luz Villa\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/person\\\/e5b585c0a62172df0d10c08c6875858b\"},\"headline\":\"O que h\u00e1 na geladeira de um cientista alimentar?\",\"datePublished\":\"2015-11-18T11:27:35+00:00\",\"dateModified\":\"2025-10-14T08:20:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cientifico.jpg\",\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/\",\"url\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/\",\"name\":\"O que h\u00e1 na geladeira de um cientista alimentar? - IDRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cientifico.jpg\",\"datePublished\":\"2015-11-18T11:27:35+00:00\",\"dateModified\":\"2025-10-14T08:20:27+00:00\",\"description\":\"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cientifico.jpg\",\"contentUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/cientifico.jpg\",\"width\":810,\"height\":360,\"caption\":\"HPP Cient\u00edfico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/whats-in-a-food-scientists-fridge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"IDRO - HPP\",\"item\":\"https:\\\/\\\/idro.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcia\",\"item\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/categoria\\\/noticia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O que h\u00e1 na geladeira de um cientista alimentar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idro.es\\\/#website\",\"url\":\"https:\\\/\\\/idro.es\\\/\",\"name\":\"IDRO\",\"description\":\"HPP Food Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idro.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\",\"name\":\"Idro\",\"url\":\"https:\\\/\\\/idro.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo_header7.jpg\",\"contentUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo_header7.jpg\",\"width\":648,\"height\":149,\"caption\":\"Idro\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCThdYuqEo6cvevQbZBVlDqg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idro-hpp-food-technology-s-l\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/person\\\/e5b585c0a62172df0d10c08c6875858b\",\"name\":\"M\u00aa Luz Villa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"caption\":\"M\u00aa Luz Villa\"},\"description\":\"Especializada en ofrecer el servicio de maquila de Altas Presiones Hidrost\u00e1ticas (HPP). Su trabajo combina conocimiento del sector con estrategias de marketing industrial B2B, desarrollando contenidos especializados sobre tecnolog\u00eda HPP, seguridad alimentaria y conservaci\u00f3n en fr\u00edo.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idro-hpp-food-technology-s-l\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCThdYuqEo6cvevQbZBVlDqg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que h\u00e1 na geladeira de um cientista alimentar? - IDRO","description":"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/","og_locale":"pt_PT","og_type":"article","og_title":"O que h\u00e1 na geladeira de um cientista alimentar? - IDRO","og_description":"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.","og_url":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/","og_site_name":"IDRO","article_published_time":"2015-11-18T11:27:35+00:00","article_modified_time":"2025-10-14T08:20:27+00:00","og_image":[{"width":810,"height":360,"url":"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg","type":"image\/jpeg"}],"author":"M\u00aa Luz Villa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"M\u00aa Luz Villa","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#article","isPartOf":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/"},"author":{"name":"M\u00aa Luz Villa","@id":"https:\/\/idro.es\/#\/schema\/person\/e5b585c0a62172df0d10c08c6875858b"},"headline":"O que h\u00e1 na geladeira de um cientista alimentar?","datePublished":"2015-11-18T11:27:35+00:00","dateModified":"2025-10-14T08:20:27+00:00","mainEntityOfPage":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/"},"wordCount":283,"publisher":{"@id":"https:\/\/idro.es\/#organization"},"image":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#primaryimage"},"thumbnailUrl":"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg","articleSection":["Not\u00edcia"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/","url":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/","name":"O que h\u00e1 na geladeira de um cientista alimentar? - IDRO","isPartOf":{"@id":"https:\/\/idro.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#primaryimage"},"image":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#primaryimage"},"thumbnailUrl":"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg","datePublished":"2015-11-18T11:27:35+00:00","dateModified":"2025-10-14T08:20:27+00:00","description":"Descubra quais alimentos e bebidas HPP nossos cientistas de alimentos armazenam em suas geladeiras pessoais.","breadcrumb":{"@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#primaryimage","url":"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg","contentUrl":"https:\/\/idro.es\/wp-content\/uploads\/2014\/11\/cientifico.jpg","width":810,"height":360,"caption":"HPP Cient\u00edfico"},{"@type":"BreadcrumbList","@id":"https:\/\/idro.es\/pt-pt\/whats-in-a-food-scientists-fridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"IDRO - HPP","item":"https:\/\/idro.es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcia","item":"https:\/\/idro.es\/pt-pt\/categoria\/noticia\/"},{"@type":"ListItem","position":3,"name":"O que h\u00e1 na geladeira de um cientista alimentar?"}]},{"@type":"WebSite","@id":"https:\/\/idro.es\/#website","url":"https:\/\/idro.es\/","name":"IDRO","description":"HPP Food Technology","publisher":{"@id":"https:\/\/idro.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idro.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/idro.es\/#organization","name":"Idro","url":"https:\/\/idro.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/idro.es\/#\/schema\/logo\/image\/","url":"https:\/\/idro.es\/wp-content\/uploads\/2015\/09\/logo_header7.jpg","contentUrl":"https:\/\/idro.es\/wp-content\/uploads\/2015\/09\/logo_header7.jpg","width":648,"height":149,"caption":"Idro"},"image":{"@id":"https:\/\/idro.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCThdYuqEo6cvevQbZBVlDqg","https:\/\/www.linkedin.com\/company\/idro-hpp-food-technology-s-l\/"]},{"@type":"Person","@id":"https:\/\/idro.es\/#\/schema\/person\/e5b585c0a62172df0d10c08c6875858b","name":"M\u00aa Luz Villa","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","caption":"M\u00aa Luz Villa"},"description":"Especializada en ofrecer el servicio de maquila de Altas Presiones Hidrost\u00e1ticas (HPP). Su trabajo combina conocimiento del sector con estrategias de marketing industrial B2B, desarrollando contenidos especializados sobre tecnolog\u00eda HPP, seguridad alimentaria y conservaci\u00f3n en fr\u00edo.","sameAs":["https:\/\/www.linkedin.com\/company\/idro-hpp-food-technology-s-l\/","https:\/\/www.youtube.com\/channel\/UCThdYuqEo6cvevQbZBVlDqg"]}]}},"_links":{"self":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts\/4764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=4764"}],"version-history":[{"count":0,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts\/4764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/media\/5421"}],"wp:attachment":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=4764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=4764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=4764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}