{"id":12176,"date":"2023-05-29T09:03:44","date_gmt":"2023-05-29T09:03:44","guid":{"rendered":"https:\/\/idro.es\/?p=12176"},"modified":"2023-10-04T15:06:38","modified_gmt":"2023-10-04T15:06:38","slug":"servicio-maquila-hpp","status":"publish","type":"post","link":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/","title":{"rendered":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?"},"content":{"rendered":"<p>O conceito de maquila de produtos refere-se, em sua forma ampla, \u00e0quelas atividades produtivas de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Ou seja, \u00e9 uma produ\u00e7\u00e3o \u201cpor conta alheia\u201d cujo principal objetivo \u00e9 reduzir custos e entregar vantagens competitivas.<\/p>\n<p>Se relacionarmos esse conceito, tamb\u00e9m conhecido como ped\u00e1gio com Altas Press\u00f5es, o resultado \u00e9 um servi\u00e7o prestado por algumas empresas chamadas de fornecedores a outras chamadas de clientes, em um processo de pasteuriza\u00e7\u00e3o &#8216;frio&#8217;, n\u00e3o t\u00e9rmico, que utiliza altas press\u00f5es para desativar pat\u00f3genos ( Listeria monocytogenes e Salmonella, entre outras) em alimentos, devolvendo o produto ao seu cliente para posterior comercializa\u00e7\u00e3o. Oferecer uma solu\u00e7\u00e3o completa sem a necessidade de grandes investimentos, permitindo que voc\u00ea foque em seu core business, aumente sua competitividade e alcance novos mercados.<\/p>\n<p>Como podemos ver no gr\u00e1fico seguinte, a evolu\u00e7\u00e3o do n\u00famero de m\u00e1quinas instaladas disparou desde o in\u00edcio do s\u00e9culo XXI.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/maquinas-HPP-en-produccion.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-12168\" src=\"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/maquinas-HPP-en-produccion.png\" alt=\"Crecimiento de m\u00e1quinas instaladas de HPP\" width=\"505\" height=\"305\" srcset=\"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/maquinas-HPP-en-produccion.png 505w, https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/maquinas-HPP-en-produccion-300x181.png 300w\" sizes=\"(max-width: 505px) 100vw, 505px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>As vantagens da implementa\u00e7\u00e3o comercial de processos de alta press\u00e3o s\u00e3o importantes raz\u00f5es pelas quais esta tecnologia chegou ao consumidor em um curto espa\u00e7o de tempo com uma grande variedade de produtos. Por esses motivos, o n\u00famero de equipes comerciais que atuam no mundo aumentou nos \u00faltimos anos, e isso \u00e9 um sinal de que as empresas est\u00e3o apostando em aumentar a diversidade de seus produtos e melhorar sua qualidade.<\/p>\n<p>Algumas das empresas aliment\u00edcias mais poderosas da Espanha, junto com institutos tecnol\u00f3gicos, t\u00eam a seu cr\u00e9dito uma m\u00e1quina dessas caracter\u00edsticas, mas a maioria opta pelo servi\u00e7o de maquila. <strong>A nossa empresa (IDRO) lidera atualmente o mercado de Alta Press\u00e3o em Madrid, posicionando-nos como uma das mais poderosas a n\u00edvel nacional no nosso setor.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alimentos de origen animal, como carnes y productos c\u00e1rnicos, huevos y preparados de huevos (crudos o poco cocidos) y productos de la pesca, est\u00e1n implicados en el 70% de los brotes. Las salmonelas est\u00e1n implicadas en m\u00e1s de la mitad de los brotes relacionados con las carnes y en casi todos los asociados con los huevos y preparaciones de huevo.\u00a0Campylobacter\u00a0participa en el 17% de los brotes asociados a las carnes. Los asociados con productos de la pesca incluyen histamina (el 72% por pescados) en el 40% de los casos y norovirus en el 34% de los casos (73% de los brotes asociados con bivalvos). Los platos preparados con m\u00faltiples ingredientes se relacionan con el 21% de los brotes.<\/p>\n","protected":false},"author":4,"featured_media":12174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[254],"tags":[327,339,90,321,322,302,57,344,345],"class_list":["post-12176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-alerta-sanitaria-pt-pt","tag-conservacion-pt-pt","tag-hpp-pt-pt","tag-idro-pt-pt","tag-ifs-pt-pt","tag-maquila-pt-pt","tag-vegetales-pt-pt","tag-vegetarianos-pt-pt","tag-veggies-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 o servi\u00e7o de maquilhagem HPP?<\/title>\n<meta name=\"description\" content=\"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 o servi\u00e7o de maquilhagem HPP?\" \/>\n<meta property=\"og:description\" content=\"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/\" \/>\n<meta property=\"og:site_name\" content=\"IDRO\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-29T09:03:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T15:06:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00aa Luz Villa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00aa Luz Villa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/\"},\"author\":{\"name\":\"M\u00aa Luz Villa\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/person\\\/e5b585c0a62172df0d10c08c6875858b\"},\"headline\":\"O que \u00e9 o servi\u00e7o de maquilhagem HPP?\",\"datePublished\":\"2023-05-29T09:03:44+00:00\",\"dateModified\":\"2023-10-04T15:06:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/\"},\"wordCount\":313,\"publisher\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Equipo-HPP-de-Avure.jpg\",\"keywords\":[\"alerta sanitaria\",\"conservacion\",\"hpp\",\"IDRO\",\"IFS\",\"maquila\",\"vegetales\",\"vegetarianos\",\"veggies\"],\"articleSection\":[\"Not\u00edcia\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/\",\"url\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/\",\"name\":\"O que \u00e9 o servi\u00e7o de maquilhagem HPP?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Equipo-HPP-de-Avure.jpg\",\"datePublished\":\"2023-05-29T09:03:44+00:00\",\"dateModified\":\"2023-10-04T15:06:38+00:00\",\"description\":\"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Equipo-HPP-de-Avure.jpg\",\"contentUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Equipo-HPP-de-Avure.jpg\",\"width\":535,\"height\":357,\"caption\":\"Servicio maquila HPP en IDRO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idro.es\\\/pt-pt\\\/servicio-maquila-hpp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"IDRO - HPP\",\"item\":\"https:\\\/\\\/idro.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/idro.es\\\/categoria\\\/entradas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O que \u00e9 o servi\u00e7o de maquilhagem HPP?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idro.es\\\/#website\",\"url\":\"https:\\\/\\\/idro.es\\\/\",\"name\":\"IDRO\",\"description\":\"HPP Food Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idro.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idro.es\\\/#organization\",\"name\":\"Idro\",\"url\":\"https:\\\/\\\/idro.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo_header7.jpg\",\"contentUrl\":\"https:\\\/\\\/idro.es\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/logo_header7.jpg\",\"width\":648,\"height\":149,\"caption\":\"Idro\"},\"image\":{\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCThdYuqEo6cvevQbZBVlDqg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idro-hpp-food-technology-s-l\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/idro.es\\\/#\\\/schema\\\/person\\\/e5b585c0a62172df0d10c08c6875858b\",\"name\":\"M\u00aa Luz Villa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g\",\"caption\":\"M\u00aa Luz Villa\"},\"description\":\"Especializada en ofrecer el servicio de maquila de Altas Presiones Hidrost\u00e1ticas (HPP). Su trabajo combina conocimiento del sector con estrategias de marketing industrial B2B, desarrollando contenidos especializados sobre tecnolog\u00eda HPP, seguridad alimentaria y conservaci\u00f3n en fr\u00edo.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idro-hpp-food-technology-s-l\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCThdYuqEo6cvevQbZBVlDqg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?","description":"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/","og_locale":"pt_PT","og_type":"article","og_title":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?","og_description":"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.","og_url":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/","og_site_name":"IDRO","article_published_time":"2023-05-29T09:03:44+00:00","article_modified_time":"2023-10-04T15:06:38+00:00","og_image":[{"width":535,"height":357,"url":"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg","type":"image\/jpeg"}],"author":"M\u00aa Luz Villa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"M\u00aa Luz Villa","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#article","isPartOf":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/"},"author":{"name":"M\u00aa Luz Villa","@id":"https:\/\/idro.es\/#\/schema\/person\/e5b585c0a62172df0d10c08c6875858b"},"headline":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?","datePublished":"2023-05-29T09:03:44+00:00","dateModified":"2023-10-04T15:06:38+00:00","mainEntityOfPage":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/"},"wordCount":313,"publisher":{"@id":"https:\/\/idro.es\/#organization"},"image":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#primaryimage"},"thumbnailUrl":"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg","keywords":["alerta sanitaria","conservacion","hpp","IDRO","IFS","maquila","vegetales","vegetarianos","veggies"],"articleSection":["Not\u00edcia"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/","url":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/","name":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?","isPartOf":{"@id":"https:\/\/idro.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#primaryimage"},"image":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#primaryimage"},"thumbnailUrl":"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg","datePublished":"2023-05-29T09:03:44+00:00","dateModified":"2023-10-04T15:06:38+00:00","description":"Maquila de produtos refere-se atividades de uma empresa que s\u00e3o enviadas a outra para serem realizadas. Reduzir custos e entregar vantagens competitivas.","breadcrumb":{"@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#primaryimage","url":"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg","contentUrl":"https:\/\/idro.es\/wp-content\/uploads\/2023\/05\/Equipo-HPP-de-Avure.jpg","width":535,"height":357,"caption":"Servicio maquila HPP en IDRO"},{"@type":"BreadcrumbList","@id":"https:\/\/idro.es\/pt-pt\/servicio-maquila-hpp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"IDRO - HPP","item":"https:\/\/idro.es\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/idro.es\/categoria\/entradas\/"},{"@type":"ListItem","position":3,"name":"O que \u00e9 o servi\u00e7o de maquilhagem HPP?"}]},{"@type":"WebSite","@id":"https:\/\/idro.es\/#website","url":"https:\/\/idro.es\/","name":"IDRO","description":"HPP Food Technology","publisher":{"@id":"https:\/\/idro.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idro.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/idro.es\/#organization","name":"Idro","url":"https:\/\/idro.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/idro.es\/#\/schema\/logo\/image\/","url":"https:\/\/idro.es\/wp-content\/uploads\/2015\/09\/logo_header7.jpg","contentUrl":"https:\/\/idro.es\/wp-content\/uploads\/2015\/09\/logo_header7.jpg","width":648,"height":149,"caption":"Idro"},"image":{"@id":"https:\/\/idro.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCThdYuqEo6cvevQbZBVlDqg","https:\/\/www.linkedin.com\/company\/idro-hpp-food-technology-s-l\/"]},{"@type":"Person","@id":"https:\/\/idro.es\/#\/schema\/person\/e5b585c0a62172df0d10c08c6875858b","name":"M\u00aa Luz Villa","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c909fc47e24ea39f86ac947fd99f8dd6dd4836919c6b627d66cb5696c41c97c?s=96&d=mm&r=g","caption":"M\u00aa Luz Villa"},"description":"Especializada en ofrecer el servicio de maquila de Altas Presiones Hidrost\u00e1ticas (HPP). Su trabajo combina conocimiento del sector con estrategias de marketing industrial B2B, desarrollando contenidos especializados sobre tecnolog\u00eda HPP, seguridad alimentaria y conservaci\u00f3n en fr\u00edo.","sameAs":["https:\/\/www.linkedin.com\/company\/idro-hpp-food-technology-s-l\/","https:\/\/www.youtube.com\/channel\/UCThdYuqEo6cvevQbZBVlDqg"]}]}},"_links":{"self":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts\/12176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=12176"}],"version-history":[{"count":0,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/posts\/12176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/media\/12174"}],"wp:attachment":[{"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=12176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=12176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idro.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=12176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}